
{"id":226690,"date":"2019-08-13T16:22:52","date_gmt":"2019-08-13T15:22:52","guid":{"rendered":"http:\/\/kyb-europe.com\/iberia\/?p=15023"},"modified":"2021-08-31T11:51:35","modified_gmt":"2021-08-31T10:51:35","slug":"mas-mejoras-en-el-horizonte-de-los-datos-de-kyb","status":"publish","type":"post","link":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/","title":{"rendered":"M\u00e1s mejoras en el horizonte de los datos de KYB"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">KYB anuncia m\u00e1s mejoras en sus datos y en su visibilidad en TecDoc. Recientemente se ha revelado que KYB mantiene su estatus de proveedor con clasificaci\u00f3n A para TecAlliance. Contamos con un equipo especializado formado por personas que trabajan a tiempo completo para garantizar que los datos del cat\u00e1logo KYB est\u00e9n actualizados y sean precisos, asegurando que los clientes tengan acceso a la informaci\u00f3n m\u00e1s pertinente. Para ser distinguido como proveedor con clasificaci\u00f3n A, las descripciones de los productos deben cumplir, al menos, con un 99% de los est\u00e1ndares TecAlliance.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A lo ya expuesto se le suma que KYB ha sido escogido para ser incluido en un proyecto piloto de TecAlliance en que los nuevos datos que se incorporar\u00e1n en TecDoc, estar\u00e1n disponibles en 6 d\u00edas (una considerable mejora frente al mes y medio actual). La prueba piloto se ha puesto en marcha en agosto de 2019. KYB puede afirmar ya, ser l\u00edder del mercado en lo que respecta a la nueva gama de amortiguadores (los datos m\u00e1s recientes del parque automovil\u00edstico demuestran que la gama KYB supera a su competidor m\u00e1s cercano en m\u00e1s de 5 millones de autom\u00f3viles europeos cubiertos con menos de 5 a\u00f1os) y esto solo puede mejorar, siendo como es KYB uno de los pocos fabricantes importantes de amortiguadores elegidos para esta gran mejora con objeto de agilizar la visibilidad de los datos.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u00abPor varias razones, KYB est\u00e1 listo para comercializar nuevos amortiguadores de forma m\u00e1s r\u00e1pida que cualquier otro fabricante \u00bb, explica Jean Fran\u00e7ois Huan, Director General de Gesti\u00f3n de Productos de KYB Europe Aftermarket. \u00abKYB es primer equipo de 1 de cada 5 coches en el mundo, lo que significa que somos los primeros en comercializar, de forma directa, estas unidades. Para el resto, tenemos departamentos de investigaci\u00f3n por todo el mundo, una gran instalaci\u00f3n para el<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">desarrollo tecnol\u00f3gico en Jap\u00f3n y un centro de pruebas y experimentaci\u00f3n aqu\u00ed, en Francia. Tener la capacidad de a\u00f1adir nuevos datos en TecDoc, en 6 d\u00edas, es el siguiente paso para que nuestro producto est\u00e9 disponible y sea visible para nuestros clientes antes que otros\u00bb.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>KYB anuncia m\u00e1s mejoras en sus datos y en su<a href=\"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/\">&#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":226725,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-226690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nota-de-prensa"],"acf":[],"featured_media_global":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s mejoras en el horizonte de los datos de KYB - Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s mejoras en el horizonte de los datos de KYB - Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"KYB anuncia m\u00e1s mejoras en sus datos y en su...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-13T15:22:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-31T10:51:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kyb-europe.com\/iberia\/wp-content\/uploads\/sites\/38\/2019\/08\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"993\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sueclough\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sueclough\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/\"},\"author\":{\"name\":\"sueclough\",\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/#\\\/schema\\\/person\\\/ff46991e9eec3c8ee4075b215954a453\"},\"headline\":\"M\u00e1s mejoras en el horizonte de los datos de KYB\",\"datePublished\":\"2019-08-13T15:22:52+00:00\",\"dateModified\":\"2021-08-31T10:51:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/\"},\"wordCount\":380,\"image\":{\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2019\\\/08\\\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg\",\"articleSection\":[\"Nota de prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/\",\"url\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/\",\"name\":\"M\u00e1s mejoras en el horizonte de los datos de KYB - Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2019\\\/08\\\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg\",\"datePublished\":\"2019-08-13T15:22:52+00:00\",\"dateModified\":\"2021-08-31T10:51:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/#\\\/schema\\\/person\\\/ff46991e9eec3c8ee4075b215954a453\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2019\\\/08\\\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg\",\"contentUrl\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2019\\\/08\\\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg\",\"width\":993,\"height\":373},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/#website\",\"url\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/\",\"name\":\"Espa\u00f1ol\",\"description\":\"Our Precision, Your Advantage\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/#\\\/schema\\\/person\\\/ff46991e9eec3c8ee4075b215954a453\",\"name\":\"sueclough\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43891ec13d5d8c278782a69cbfddde82f11b9005f84c6f4d816780e3d4f4fa06?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43891ec13d5d8c278782a69cbfddde82f11b9005f84c6f4d816780e3d4f4fa06?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43891ec13d5d8c278782a69cbfddde82f11b9005f84c6f4d816780e3d4f4fa06?s=96&d=mm&r=g\",\"caption\":\"sueclough\"},\"url\":\"https:\\\/\\\/kyb-europe.com\\\/iberia\\\/blog\\\/author\\\/sueclough\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s mejoras en el horizonte de los datos de KYB - Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s mejoras en el horizonte de los datos de KYB - Espa\u00f1ol","og_description":"KYB anuncia m\u00e1s mejoras en sus datos y en su...","og_url":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/","og_site_name":"Espa\u00f1ol","article_published_time":"2019-08-13T15:22:52+00:00","article_modified_time":"2021-08-31T10:51:35+00:00","og_image":[{"width":993,"height":373,"url":"https:\/\/kyb-europe.com\/iberia\/wp-content\/uploads\/sites\/38\/2019\/08\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg","type":"image\/jpeg"}],"author":"sueclough","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sueclough","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/#article","isPartOf":{"@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/"},"author":{"name":"sueclough","@id":"https:\/\/kyb-europe.com\/iberia\/#\/schema\/person\/ff46991e9eec3c8ee4075b215954a453"},"headline":"M\u00e1s mejoras en el horizonte de los datos de KYB","datePublished":"2019-08-13T15:22:52+00:00","dateModified":"2021-08-31T10:51:35+00:00","mainEntityOfPage":{"@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/"},"wordCount":380,"image":{"@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/#primaryimage"},"thumbnailUrl":"https:\/\/kyb-europe.com\/iberia\/wp-content\/uploads\/sites\/38\/2019\/08\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg","articleSection":["Nota de prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/","url":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/","name":"M\u00e1s mejoras en el horizonte de los datos de KYB - Espa\u00f1ol","isPartOf":{"@id":"https:\/\/kyb-europe.com\/iberia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/#primaryimage"},"image":{"@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/#primaryimage"},"thumbnailUrl":"https:\/\/kyb-europe.com\/iberia\/wp-content\/uploads\/sites\/38\/2019\/08\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg","datePublished":"2019-08-13T15:22:52+00:00","dateModified":"2021-08-31T10:51:35+00:00","author":{"@id":"https:\/\/kyb-europe.com\/iberia\/#\/schema\/person\/ff46991e9eec3c8ee4075b215954a453"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kyb-europe.com\/iberia\/blog\/mas-mejoras-en-el-horizonte-de-los-datos-de-kyb\/#primaryimage","url":"https:\/\/kyb-europe.com\/iberia\/wp-content\/uploads\/sites\/38\/2019\/08\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg","contentUrl":"https:\/\/kyb-europe.com\/iberia\/wp-content\/uploads\/sites\/38\/2019\/08\/tca_certified-data-supplier_logo_cmyk_300dpi-1.jpg","width":993,"height":373},{"@type":"WebSite","@id":"https:\/\/kyb-europe.com\/iberia\/#website","url":"https:\/\/kyb-europe.com\/iberia\/","name":"Espa\u00f1ol","description":"Our Precision, Your Advantage","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kyb-europe.com\/iberia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/kyb-europe.com\/iberia\/#\/schema\/person\/ff46991e9eec3c8ee4075b215954a453","name":"sueclough","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/43891ec13d5d8c278782a69cbfddde82f11b9005f84c6f4d816780e3d4f4fa06?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43891ec13d5d8c278782a69cbfddde82f11b9005f84c6f4d816780e3d4f4fa06?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43891ec13d5d8c278782a69cbfddde82f11b9005f84c6f4d816780e3d4f4fa06?s=96&d=mm&r=g","caption":"sueclough"},"url":"https:\/\/kyb-europe.com\/iberia\/blog\/author\/sueclough\/"}]}},"_links":{"self":[{"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/posts\/226690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/comments?post=226690"}],"version-history":[{"count":1,"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/posts\/226690\/revisions"}],"predecessor-version":[{"id":226726,"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/posts\/226690\/revisions\/226726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/media\/226725"}],"wp:attachment":[{"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/media?parent=226690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/categories?post=226690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kyb-europe.com\/iberia\/wp-json\/wp\/v2\/tags?post=226690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}